{"id":161,"count":1,"description":"","link":"http:\/\/earbirding.com\/blog\/archives\/tag\/spectrogram-iphone-application","name":"Spectrogram iPhone application","slug":"spectrogram-iphone-application","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/earbirding.com\/blog\/wp-json\/wp\/v2\/tags\/161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/earbirding.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/earbirding.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/earbirding.com\/blog\/wp-json\/wp\/v2\/posts?tags=161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}